{"id":341,"count":18,"description":"HighOnLove introduz misturas de lubrificantes de grau superior feitas com \u00f3leo de c\u00e2nhamo. Esta linha de produtos traz estilo e intimidade acrescidos, para quem sabe o que quer no quarto.\n\nUtilizando apenas o mais luxuoso \u00f3leo de sementes de c\u00e2nhamo e ingredientes ricos em nutrientes dos fornecedores internacionais da mais alta qualidade, HighOnLove \u00e9 alquimia ao seu melhor. Influenciadas pelos melhores cosm\u00e9ticos do mundo, estas f\u00f3rmulas amigas da pele proporcionam experi\u00eancias \u00edntimas revolucion\u00e1rias e um n\u00edvel de estimula\u00e7\u00e3o que s\u00f3 o \u00f3leo de semente de c\u00e2nhamo pode proporcionar.\n\nOs produtos HighOnLove s\u00e3o cinecologicamente testados, sem qu\u00edmicos, vegan e sem crueldade. Fabricados com ingredientes premium, 100% naturais, os produtos HighOnLove n\u00e3o cont\u00eam sab\u00e3o, parabenos, alerg\u00e9nicos ou corantes.","link":"https:\/\/carmogepereira.pt\/pt\/brand\/highonlove\/","name":"HighOnLove","slug":"highonlove","taxonomy":"pwb-brand","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/carmogepereira.pt\/pt\/wp-json\/wp\/v2\/pwb-brand\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmogepereira.pt\/pt\/wp-json\/wp\/v2\/pwb-brand"}],"about":[{"href":"https:\/\/carmogepereira.pt\/pt\/wp-json\/wp\/v2\/taxonomies\/pwb-brand"}],"wp:post_type":[{"href":"https:\/\/carmogepereira.pt\/pt\/wp-json\/wp\/v2\/product?pwb-brand=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}